{"id":13,"date":"2019-11-11T11:48:14","date_gmt":"2019-11-11T10:48:14","guid":{"rendered":"https:\/\/www.unitas.ch\/servizio-giovani\/?page_id=13"},"modified":"2026-01-12T09:57:40","modified_gmt":"2026-01-12T08:57:40","slug":"chi-siamo","status":"publish","type":"page","link":"https:\/\/www.unitas.ch\/servizio-giovani\/chi-siamo\/","title":{"rendered":"chi siamo"},"content":{"rendered":"\n<p>Nell\u2019aprile del 2006 la Unitas apre a Tenero un Servizio per assicurare ai giovani con andicap visivo (ciechi, ipovedenti o difficolt\u00e0 percettive)&nbsp;un <strong>accompagnamento dalla nascita fino ai 20 anni<\/strong>.&nbsp;Nato come Casa Sorriso Bambini, nel 2011 cambia nome in Servizio giovani ciechi e ipovedenti.&nbsp;Nel 2008 viene aperto il <strong>Centro Terapie<\/strong> (Low Vision, Ergoterapia e Mobilit\u00e0), situato dapprima a Bedano, poi a <strong>Ponte Capriasca<\/strong> ed ora a Porza. Il Servizio Giovani \u00e8 il centro di competenza riconosciuto come partner dal Canton Ticino e dal Canton Grigioni per le prestazioni di pedagogia specializzata in ambito visivo.<\/p>\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\" id=\"come-operiamo-speaker-break-time-200ms\"><strong>Come operiamo<\/strong>  <\/h2>\n\n\n\n<p>La nostra <strong>\u00e9quipe<\/strong> \u00e8 composta da 4 operatrici formate e con esperienza nei rispettivi ambiti di competenza. Lavoriamo per tutto il territorio del Ticino e del Moesano. Le terapie e le valutazioni sono svolte prevalentemente a Porza e Tenero. Per casi motivati possiamo recarci a domicilio o nelle scuole.<\/p>\n\n\n\n<p>Su segnalazione di genitori, medici, terapisti e docenti, si assicura un<strong> supporto mirato<\/strong> con <strong>Osservazioni e Valutazioni della Visione Funzionale<\/strong> (reale utilizzo del Potenziale visivo nella quotidianit\u00e0). Si collabora nei vari progetti individuali partecipando a riunioni di Rete. <\/p>\n\n\n\n<div style=\"height:70px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lo scopo del servizio giovani \u00e8 assicurare ai giovani con andicap visivo (ciechi, ipovedenti o difficolt\u00e0 percettive)\u00a0un accompagnamento dalla nascita fino ai 20 anni.\u00a0Su segnalazione di genitori, medici, terapisti e docenti, si assicura un supporto mirato con Osservazioni e Valutazioni della Visione Funzionale (reale utilizzo del Potenziale visivo nella quotidianit\u00e0). Si collabora nei vari progetti individuali partecipando a riunioni di Rete.<\/p>\n","protected":false},"author":3,"featured_media":180,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"page-about.php","meta":{"footnotes":""},"class_list":["post-13","page","type-page","status-publish","has-post-thumbnail","hentry"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 03:33:27","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.unitas.ch\/servizio-giovani\/wp-json\/wp\/v2\/pages\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unitas.ch\/servizio-giovani\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.unitas.ch\/servizio-giovani\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.unitas.ch\/servizio-giovani\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unitas.ch\/servizio-giovani\/wp-json\/wp\/v2\/comments?post=13"}],"version-history":[{"count":13,"href":"https:\/\/www.unitas.ch\/servizio-giovani\/wp-json\/wp\/v2\/pages\/13\/revisions"}],"predecessor-version":[{"id":260,"href":"https:\/\/www.unitas.ch\/servizio-giovani\/wp-json\/wp\/v2\/pages\/13\/revisions\/260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unitas.ch\/servizio-giovani\/wp-json\/wp\/v2\/media\/180"}],"wp:attachment":[{"href":"https:\/\/www.unitas.ch\/servizio-giovani\/wp-json\/wp\/v2\/media?parent=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}